{"id":7671,"date":"2024-09-04T02:51:59","date_gmt":"2024-09-04T07:51:59","guid":{"rendered":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-163\/"},"modified":"2024-09-05T03:06:23","modified_gmt":"2024-09-05T08:06:23","slug":"music-area-convocation-163","status":"publish","type":"tribe_events","link":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-163\/","title":{"rendered":"Music Area Convocation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":118,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-7671","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":1,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7671\/revisions"}],"predecessor-version":[{"id":7780,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7671\/revisions\/7780"}],"wp:attachment":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/media?parent=7671"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tags?post=7671"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events_cat?post=7671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}