{"id":7448,"date":"2024-08-19T21:39:48","date_gmt":"2024-08-20T02:39:48","guid":{"rendered":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-103\/"},"modified":"2024-08-23T23:05:29","modified_gmt":"2024-08-24T04:05:29","slug":"music-area-convocation-103","status":"publish","type":"tribe_events","link":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-103\/","title":{"rendered":"Music Area Convocation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":118,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-7448","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":1,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7448\/revisions"}],"predecessor-version":[{"id":7552,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7448\/revisions\/7552"}],"wp:attachment":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/media?parent=7448"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tags?post=7448"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events_cat?post=7448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}