{"id":7416,"date":"2024-08-19T21:39:44","date_gmt":"2024-08-20T02:39:44","guid":{"rendered":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-71\/"},"modified":"2024-08-23T23:05:27","modified_gmt":"2024-08-24T04:05:27","slug":"music-area-convocation-71","status":"publish","type":"tribe_events","link":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-71\/","title":{"rendered":"Music Area Convocation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":118,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-7416","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":1,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7416\/revisions"}],"predecessor-version":[{"id":7520,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7416\/revisions\/7520"}],"wp:attachment":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/media?parent=7416"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tags?post=7416"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events_cat?post=7416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}