{"id":7403,"date":"2024-08-19T21:39:43","date_gmt":"2024-08-20T02:39:43","guid":{"rendered":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-58\/"},"modified":"2024-08-23T23:05:26","modified_gmt":"2024-08-24T04:05:26","slug":"music-area-convocation-58","status":"publish","type":"tribe_events","link":"https:\/\/www.missouriwestern.edu\/sfa\/event\/music-area-convocation-58\/","title":{"rendered":"Music Area Convocation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":118,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-7403","tribe_events","type-tribe_events","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/users\/118"}],"version-history":[{"count":1,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7403\/revisions"}],"predecessor-version":[{"id":7507,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events\/7403\/revisions\/7507"}],"wp:attachment":[{"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/media?parent=7403"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tags?post=7403"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/sfa\/wp-json\/wp\/v2\/tribe_events_cat?post=7403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}